{"id":5,"date":"2023-07-04T02:38:40","date_gmt":"2023-07-04T02:38:40","guid":{"rendered":"https:\/\/hys.ar\/?p=5"},"modified":"2023-07-04T13:13:35","modified_gmt":"2023-07-04T13:13:35","slug":"como-influye-en-el-trabajo-la-ley-de-higiene-y-seguridad-laboral-a-casi-medio-siglo-de-su-sancion","status":"publish","type":"post","link":"https:\/\/hys.ar\/index.php\/2023\/07\/04\/como-influye-en-el-trabajo-la-ley-de-higiene-y-seguridad-laboral-a-casi-medio-siglo-de-su-sancion\/","title":{"rendered":"C\u00f3mo influye en el trabajo la ley de Higiene y Seguridad Laboral, a casi medio siglo de su sanci\u00f3n"},"content":{"rendered":"\n<p>Es de suma importancia promover una cultura de prevenci\u00f3n mediante la educaci\u00f3n y la anticipaci\u00f3n<\/p>\n\n\n\n<p><mark><strong>Se conmemor\u00f3 en la Argentina el D\u00eda de la Higiene y Seguridad Laboral, a 49 a\u00f1os de la sanci\u00f3n de su ley<\/strong><\/mark>. La legislaci\u00f3n 19587\/72 fue el puntapi\u00e9 inicial de lo que es hoy un estilo de vida personal, en cada provincia a nivel nacional, donde el m\u00e9rito no se encuentra en la agenda diaria de todos esos estudiantes y profesionales matriculados, tanto t\u00e9cnicos o licenciados, tan solicitados hoy en este contexto de pandemia.<\/p>\n\n\n<figure class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/hys.ar\/wp-content\/uploads\/2023\/07\/TBABR3BJKBOT7J5BUZHULDLUH4.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/hys.ar\/wp-content\/uploads\/2023\/07\/TBABR3BJKBOT7J5BUZHULDLUH4.jpg 768w, https:\/\/hys.ar\/wp-content\/uploads\/2023\/07\/TBABR3BJKBOT7J5BUZHULDLUH4-300x225.jpg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n<p>En 2003, la Organizaci\u00f3n Internacional del Trabajo (OIT) empez\u00f3 a observar el D\u00eda Mundial&nbsp;<mark><strong>haciendo hincapi\u00e9 en la prevenci\u00f3n de los accidentes y las enfermedades en el lugar de trabajo<\/strong>, apoy\u00e1ndose en las caracter\u00edsticas tradicionales que fortalecen su acci\u00f3n<\/mark>: el tripartismo y el di\u00e1logo social, abogando por el establecimiento de sistemas de seguridad y salud en el trabajo resilientes para hacer frente a futuras situaciones de emergencia.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 cambi\u00f3 como sociedad desde la creaci\u00f3n de esta ley?<\/strong><\/h4>\n\n\n\n<p>Hoy la ley est\u00e1 con miles de parches, ac\u00e9fala y anacr\u00f3nica para los tiempos que vivimos, en medio de una pandemia, no solo sanitaria sino social, que dej\u00f3 al descubierto la miseria humana y la falta de compromiso de incorporaci\u00f3n de una cambio genuino en materia de prevenci\u00f3n.<\/p>\n\n\n\n<p>Independientemente del posicionamiento ideol\u00f3gico, izquierda o derecha, la problem\u00e1tica de los riesgos y la seguridad de las personas en el \u00e1mbito laboral es trabajo de todo estamento. Por este motivo&nbsp;<mark><strong>es de suma importancia promover una cultura de prevenci\u00f3n mediante la educaci\u00f3n, la sensibilizaci\u00f3n y la anticipaci\u00f3n.<\/strong><\/mark><\/p>\n\n\n\n<p>Hoy es un buen momento para pensar este sector de la sociedad a nivel nacional con el fin de&nbsp;<strong>conmemorar, dignificar y jerarquizar una profesi\u00f3n que tambi\u00e9n tiene sus vicisitudes<\/strong>. Esto se debe a que los profesionales para ejercer deben estar matriculados y muchas provincias a\u00fan no tienen conformados sus Colegios. Este es el caso de Mendoza, que lleva m\u00e1s de 10 a\u00f1os en un periplo que comenz\u00f3 con un trabajo social y hoy es una necesidad de m\u00e1s de 9000 egresados, de los cuales 1000 solo se encuentran matriculados.<\/p>\n\n\n\n<p>En definitiva,&nbsp;<strong>debemos seguir en ese camino y ser embajadores sin claudicar<\/strong>,hasta lograr una sociedad m\u00e1s justa dado que desde un punto de vista profesional, humana y emp\u00e1tica tambi\u00e9n salvamos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es de suma importancia promover una cultura de prevenci\u00f3n mediante la educaci\u00f3n y la anticipaci\u00f3n Se conmemor\u00f3 en la Argentina el D\u00eda de la Higiene y Seguridad Laboral, a 49 a\u00f1os de la sanci\u00f3n de su ley. La legislaci\u00f3n 19587\/72 fue el puntapi\u00e9 inicial de lo que es hoy un estilo de vida personal, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/posts\/5"}],"collection":[{"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":2,"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/posts\/5\/revisions"}],"predecessor-version":[{"id":27,"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/posts\/5\/revisions\/27"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/media\/7"}],"wp:attachment":[{"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/media?parent=5"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/categories?post=5"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hys.ar\/index.php\/wp-json\/wp\/v2\/tags?post=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}